{"id":49001,"date":"2025-09-17T14:25:04","date_gmt":"2025-09-17T12:25:04","guid":{"rendered":"https:\/\/ekoenergetyka.com\/?page_id=49001"},"modified":"2026-04-17T08:59:30","modified_gmt":"2026-04-17T06:59:30","slug":"praktikum-bei-ekoenergetyka","status":"publish","type":"page","link":"https:\/\/ekoenergetyka.com\/de\/karriere\/praktikum-bei-ekoenergetyka\/","title":{"rendered":"Praktikum bei Ekoenergetyka"},"content":{"rendered":"\n<div style=\"height:4em\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<section     class=\"text-with-button   \">\n    <div class=\"container text-with-button-container\">\n                <h2 >Starte deine Karriere mit guter <span>Energie!<\/span><\/h2>\n                <div class=\"text-center\">\n            Wusstest du, dass deine berufliche Laufbahn schon vor dem Schulabschluss beginnt? Dieser Startpunkt ist ein sehr wichtiger Moment in deinem Leben. Die Entscheidungen, die du jetzt triffst, k\u00f6nnen deine gesamte berufliche Zukunft beeinflussen. Gib dir selbst also einen wirklich energiegeladenen Karrierestart!        <\/div>\n                        <a href=\"https:\/\/system.erecruiter.pl\/FormTemplates\/RecruitmentForm.aspx?WebID=65dbe44d7c8a4a178afe9c6efa3c20be\"\n            class=\"button \">Anwenden            <span>\n                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"16\" viewBox=\"0 0 15 16\" class=\"arrow-right\">\n                    <path id=\"Vector_1\"\n                        d=\"M14.9 7.52395C14.8405 7.37051 14.7513 7.23033 14.6375 7.11145L8.3875 0.861451C8.27095 0.744903 8.13259 0.652453 7.98031 0.589377C7.82803 0.526302 7.66482 0.493837 7.5 0.493837C7.16712 0.493837 6.84788 0.626072 6.6125 0.861451C6.49595 0.977999 6.4035 1.11636 6.34042 1.26864C6.27735 1.42092 6.24488 1.58413 6.24488 1.74895C6.24488 2.08183 6.37712 2.40107 6.6125 2.63645L10.7375 6.74895L1.25 6.74895C0.918478 6.74895 0.600536 6.88065 0.366116 7.11507C0.131695 7.34949 -1.25427e-06 7.66743 -1.31224e-06 7.99895C-1.3702e-06 8.33047 0.131695 8.64841 0.366115 8.88283C0.600536 9.11725 0.918478 9.24895 1.25 9.24895L10.7375 9.24895L6.6125 13.3614C6.49534 13.4777 6.40234 13.6159 6.33888 13.7682C6.27542 13.9206 6.24275 14.0839 6.24275 14.2489C6.24275 14.414 6.27542 14.5773 6.33888 14.7297C6.40234 14.882 6.49534 15.0202 6.6125 15.1364C6.7287 15.2536 6.86695 15.3466 7.01927 15.4101C7.1716 15.4735 7.33498 15.5062 7.5 15.5062C7.66501 15.5062 7.82839 15.4735 7.98072 15.4101C8.13304 15.3466 8.27129 15.2536 8.3875 15.1364L14.6375 8.88645C14.7513 8.76757 14.8405 8.62739 14.9 8.47395C15.025 8.16962 15.025 7.82828 14.9 7.52395Z\" \/>\n                <\/svg>\n            <\/span>\n        <\/a>\n                <div class=\"text-bottom\">\n            <h1 class=\"small-h1\">Praktikums- und Platzierungsprogramme \u2013 Ekoenergetyka<\/h1>        <\/div>\n                    <\/div>\n<\/section>\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:85%\">\n<h2 class=\"wp-block-heading\" id=\"h-mochtest-du-dich-weiterentwickeln-und-von-den-besten-e-mobility-expert-innen-lernen-dann-sind-unsere-praktikums-und-traineeprogramme-bei-ekoenergetyka-genau-das-richtige-fur-dich\">M\u00f6chtest du dich weiterentwickeln und von den besten E-Mobility-Expert:innen lernen? Dann sind unsere Praktikums- und Traineeprogramme bei Ekoenergetyka genau das Richtige <span style=\"color: #161412;\">f\u00fcr dich!<\/span><\/h2>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:15%\"><\/div>\n<\/div>\n\n\n<section\n    class=\"box-with-icon    \">\n    <div class=\"box-with-icon-wrapper\">\n                <div class=\"box-with-icon-title\">\n            <h2>Was du bei uns bekommst:<\/h2>\n        <\/div>\n                        <div class=\"box-with-icon-content\">\n                        <div class=\"box-with-icon-item\">\n                                <div class=\"box-with-icon-icon\">\n                    <img decoding=\"async\" src=\"https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/guidance-from-mentors-brand-experts.svg\" alt=\"Unterst\u00fctzung durch Vorgesetzte und Fachleute\" \/>\n                <\/div>\n                                <div\n                    class=\"box-with-icon-item-content \">\n                                        <div\n                        class=\"box-with-icon-title \">\n                                                <h3 class=\"big-h3\">Unterst\u00fctzung durch Vorgesetzte und Fachleute<\/h3>\n                                            <\/div>\n                                                                            <\/div>\n            <\/div>\n                        <div class=\"box-with-icon-item\">\n                                <div class=\"box-with-icon-icon\">\n                    <img decoding=\"async\" src=\"https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/internship-or-bremployment-contract.svg\" alt=\"Praktikums- oder Arbeitsvertrag\" \/>\n                <\/div>\n                                <div\n                    class=\"box-with-icon-item-content \">\n                                        <div\n                        class=\"box-with-icon-title \">\n                                                <h3 class=\"big-h3\">Praktikums- oder Arbeitsvertrag<\/h3>\n                                            <\/div>\n                                                                            <\/div>\n            <\/div>\n                        <div class=\"box-with-icon-item\">\n                                <div class=\"box-with-icon-icon\">\n                    <img decoding=\"async\" src=\"https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/option-to-extend-brthe-contract.svg\" alt=\"M\u00f6glichkeit zur Vertragsverl\u00e4ngerung\" \/>\n                <\/div>\n                                <div\n                    class=\"box-with-icon-item-content \">\n                                        <div\n                        class=\"box-with-icon-title \">\n                                                <h3 class=\"big-h3\">M\u00f6glichkeit zur Vertragsverl\u00e4ngerung<\/h3>\n                                            <\/div>\n                                                                            <\/div>\n            <\/div>\n                    <\/div>\n            <\/div>\n<\/section>\n\n<section\n    class=\"box-with-icon    \">\n    <div class=\"box-with-icon-wrapper\">\n                        <div class=\"box-with-icon-content\">\n                        <div class=\"box-with-icon-item\">\n                                <div class=\"box-with-icon-icon\">\n                    <img decoding=\"async\" src=\"https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/friendly-atmosphere-brand-integration.svg\" alt=\"Freundliches Arbeitsklima und Teamevents\" \/>\n                <\/div>\n                                <div\n                    class=\"box-with-icon-item-content \">\n                                        <div\n                        class=\"box-with-icon-title \">\n                                                <h3 class=\"big-h3\">Freundliches Arbeitsklima und Teamevents<\/h3>\n                                            <\/div>\n                                                                            <\/div>\n            <\/div>\n                        <div class=\"box-with-icon-item\">\n                                <div class=\"box-with-icon-icon\">\n                    <img decoding=\"async\" src=\"https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/internal-promotion-brwithin-the-organisation.svg\" alt=\"Aufstiegschancen innerhalb des Unternehmens\" \/>\n                <\/div>\n                                <div\n                    class=\"box-with-icon-item-content \">\n                                        <div\n                        class=\"box-with-icon-title \">\n                                                <h3 class=\"big-h3\">Aufstiegschancen innerhalb des Unternehmens<\/h3>\n                                            <\/div>\n                                                                            <\/div>\n            <\/div>\n                    <\/div>\n            <\/div>\n<\/section>\n\n<section class=\"heading-with-text\">\n    <div\n        class=\"heading-with-text-wrapper\">\n                <div class=\"heading-with-text-h2\">\n                        <h2>Praktikum <br>bei Ekoenergetyka<\/h2>\n                    <\/div>\n                        <div class=\"heading-with-text-text\">\n            <p class=\"text-big\">Wusstest du, dass deine berufliche Laufbahn schon vor dem Schulabschluss beginnt? Dieser Startpunkt ist ein entscheidender Moment in deinem Leben. Die Entscheidungen, die du jetzt triffst, k\u00f6nnen deine gesamte Karriere beeinflussen. Gib dir also einen wirklich energiegeladenen Start!<\/p>\n        <\/div>\n            <\/div>\n<\/section>\n\n<section     class=\"cards-swiper cards cards-bio \">\n        <div class=\"cards-content swiper-container\">\n        <div class=\"swiper-wrapper\">\n                            <div class=\"cards-item swiper-slide\">\n                                        <div class=\"cards-item-image\">\n                        <picture>\n                            <source srcset=\"https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/aneta-balcerzak.jpg\"\n                                media=\"(max-width: 768px)\" \/>\n                            <source srcset=\"https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/aneta-balcerzak.jpg\"\n                                media=\"(max-width: 1024px)\" \/>\n                            <source srcset=\"https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/aneta-balcerzak.jpg\"\n                                media=\"(max-width: 1920px)\" \/>\n                            <source srcset=\"https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/aneta-balcerzak.jpg\"\n                                sizes=\"100vw\" \/>\n                            <img loading=\"lazy\" decoding=\"async\" width=\"549\" height=\"895\" src=\"https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/aneta-balcerzak.jpg\" class=\"img-full\" alt=\"Aneta Balcerzak - ekoenergetyka\" \/>                        <\/picture>\n                                                <div class=\"cards-item-bio\">\n                            <p>\"Mein Studienprofil hat mich darauf ausgerichtet, Erfahrungen im Bereich Arbeitspsychologie, Organisation und Management zu sammeln. Deshalb habe ich mich f\u00fcr ein Praktikum im HR-B\u00fcro entschieden.<br>  Von meinem ersten Tag an haben sich Klaudia und Kaja liebevoll um mich gek\u00fcmmert. Mein Onboarding unterschied sich kaum von der der festen Mitarbeiter:innen. Von Anfang an war mein Zeitplan gut strukturiert, was mir Sicherheit im neuen Umfeld gab.<br>  Ich bin mit der Motivation, mich weiterzuentwickeln, zu Ekoenergetyka gekommen \u2013 und ich wurde nicht entt\u00e4uscht! Es war eine sehr gute Entscheidung!  Nach dem Praktikum bin ich als Junior HR-Spezialistin ins Team eingestiegen und arbeite inzwischen als HR-Spezialistin.\"<\/p>\n                        <\/div>\n                                            <\/div>\n                                                            <div class=\"cards-item-title\">\n                        <h3 class=\"big-h3\">Aneta Balcerzak<\/h3>\n                        <p>HR-Spezialistin<\/p>\n                    <\/div>\n                                    <\/div>\n                                            <div class=\"cards-item swiper-slide\">\n                                        <div class=\"cards-item-image\">\n                        <picture>\n                            <source srcset=\"https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/mateusz-czugala.jpg\"\n                                media=\"(max-width: 768px)\" \/>\n                            <source srcset=\"https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/mateusz-czugala.jpg\"\n                                media=\"(max-width: 1024px)\" \/>\n                            <source srcset=\"https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/mateusz-czugala.jpg\"\n                                media=\"(max-width: 1920px)\" \/>\n                            <source srcset=\"https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/mateusz-czugala.jpg\"\n                                sizes=\"100vw\" \/>\n                            <img loading=\"lazy\" decoding=\"async\" width=\"549\" height=\"895\" src=\"https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/mateusz-czugala.jpg\" class=\"img-full\" alt=\"Mateusz Czuga\u0142a - ekoenergetyka\" \/>                        <\/picture>\n                                                <div class=\"cards-item-bio\">\n                            <p>Kennt ihr das Klischee, dass Praktikant:innen nur Kaffee vornbereiten und Dokumente kopieren? Nicht hier! <br> Ich bin Student im 4. Jahrgang des Studiengangs E-Business an der Universit\u00e4t Zielona G\u00f3ra und durfte bereits beim Aufbau eines Serverraums mithelfen sowie die technische Inbetriebnahme eines neuen Geb\u00e4udes von Ekoenergetyka begleiten.<br> Tats\u00e4chlich habe ich jeden Tag etwas Neues gelernt \u2013 und es hat nie an hilfsbereiten Menschen gefehlt. Was mich besonders positiv \u00fcberrascht hat: Nicht nur mein Vorgesetzter und mein zugewiesener Betreuer haben sich Zeit f\u00fcr mich genommen, sondern jedes Teammitglied hat mich aktiv in meiner Entwicklung unterst\u00fctzt.  <\/p>\n                        <\/div>\n                                            <\/div>\n                                                            <div class=\"cards-item-title\">\n                        <h3 class=\"big-h3\">Mateusz Czuga\u0142a<\/h3>\n                        <p>IT Support Specialist<\/p>\n                    <\/div>\n                                    <\/div>\n                                            <div class=\"cards-item swiper-slide\">\n                                        <div class=\"cards-item-image\">\n                        <picture>\n                            <source srcset=\"https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/monika-ziemska.jpg\"\n                                media=\"(max-width: 768px)\" \/>\n                            <source srcset=\"https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/monika-ziemska.jpg\"\n                                media=\"(max-width: 1024px)\" \/>\n                            <source srcset=\"https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/monika-ziemska.jpg\"\n                                media=\"(max-width: 1920px)\" \/>\n                            <source srcset=\"https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/monika-ziemska.jpg\"\n                                sizes=\"100vw\" \/>\n                            <img loading=\"lazy\" decoding=\"async\" width=\"549\" height=\"895\" src=\"https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/monika-ziemska.jpg\" class=\"img-full\" alt=\"Monika Ziemska - ekoenergetyka\" \/>                        <\/picture>\n                                                <div class=\"cards-item-bio\">\n                            <p>Meiner Meinung nach sollte man ein studentisches Praktikum maximal ausnutzen \u2013 man wei\u00df nie, ob es nicht zuf\u00e4llig die T\u00fcr zur weiteren Karriere \u00f6ffnet. Genau so war es bei mir! Mein Engagement wurde gesch\u00e4tzt, und nach einem sechsmonatigen Praktikum bekam ich ein Angebot als Junior Spezialistin f\u00fcr Logistik. <br>  Zurzeit mache ich meinen Master und kombiniere mein Studium mit der Arbeit. Das Praktikum bei #EKO hat mir nicht nur wertvolle Erfahrungen im Bereich Logistik gebracht, sondern auch mein Interesse an der E-Mobility-Branche geweckt \u2013 so sehr, dass ich sogar das Thema meiner Bachelorarbeit ge\u00e4ndert habe! Ich habe \u00fcber den Stra\u00dfeng\u00fcterverkehr geschrieben. In meiner Masterarbeit werde ich mich nun auf Ladeinfrastruktur f\u00fcr den Busmarkt konzentrieren. <\/p>\n                        <\/div>\n                                            <\/div>\n                                                            <div class=\"cards-item-title\">\n                        <h3 class=\"big-h3\">Monika Ziemska<\/h3>\n                        <p>Senior Spezialistin f\u00fcr Logistik<\/p>\n                    <\/div>\n                                    <\/div>\n                                            <div class=\"cards-item swiper-slide\">\n                                        <div class=\"cards-item-image\">\n                        <picture>\n                            <source srcset=\"https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/tomasz-cwojdzinski.jpg\"\n                                media=\"(max-width: 768px)\" \/>\n                            <source srcset=\"https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/tomasz-cwojdzinski.jpg\"\n                                media=\"(max-width: 1024px)\" \/>\n                            <source srcset=\"https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/tomasz-cwojdzinski.jpg\"\n                                media=\"(max-width: 1920px)\" \/>\n                            <source srcset=\"https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/tomasz-cwojdzinski.jpg\"\n                                sizes=\"100vw\" \/>\n                            <img loading=\"lazy\" decoding=\"async\" width=\"549\" height=\"895\" src=\"https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/tomasz-cwojdzinski.jpg\" class=\"img-full\" alt=\"Artur Karczewski - ekoenergetyka\" \/>                        <\/picture>\n                                                <div class=\"cards-item-bio\">\n                            <p>Mein Weg bei Ekoenergetyka begann im Jahr 2023 mit einem Praktikum als Programmierer. Unser Team bestand damals aus drei Praktikanten, die von einem erfahrenen Mitarbeiter unterst\u00fctzt wurden. Das Projekt, an dem wir arbeiteten \u2013 ein GPS-Ortungssystem \u2013 war f\u00fcr mich eine wertvolle Erfahrung und hat mein Wissen ma\u00dfgeblich erweitert. Dieses Wissen war auch sehr hilfreich beim Verfassen meiner Ingenieurarbeit. Nach Abschluss des Praktikums erhielt ich die M\u00f6glichkeit, weiter mit dem Unternehmen zusammenzuarbeiten, und arbeite nun als Implementierungsspezialist.<\/p>\n                        <\/div>\n                                            <\/div>\n                                                            <div class=\"cards-item-title\">\n                        <h3 class=\"big-h3\">Artur Karczewski<\/h3>\n                        <p>Implementierungsspezialist<\/p>\n                    <\/div>\n                                    <\/div>\n                                            <div class=\"cards-item swiper-slide\">\n                                        <div class=\"cards-item-image\">\n                        <picture>\n                            <source srcset=\"https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/pawel-mumot.jpg\"\n                                media=\"(max-width: 768px)\" \/>\n                            <source srcset=\"https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/pawel-mumot.jpg\"\n                                media=\"(max-width: 1024px)\" \/>\n                            <source srcset=\"https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/pawel-mumot.jpg\"\n                                media=\"(max-width: 1920px)\" \/>\n                            <source srcset=\"https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/pawel-mumot.jpg\"\n                                sizes=\"100vw\" \/>\n                            <img loading=\"lazy\" decoding=\"async\" width=\"549\" height=\"895\" src=\"https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/pawel-mumot.jpg\" class=\"img-full\" alt=\"Pawe\u0142 Mumot - ekoenergetyka\" \/>                        <\/picture>\n                                                <div class=\"cards-item-bio\">\n                            <p>Einer der lokalen Journalisten hat mir den Tipp gegeben, mich bei Ekoenergetyka zu bewerben. Das ist eine zukunftstr\u00e4chtige und sehr schnell wachsende Branche. Ich bin \u00fcberzeugt, dass die Zeit hier eine gute Investition in mein berufliches Portfolio ist. Ich hoffe, die Perspektive zu bekommen, in einem gro\u00dfen Unternehmen mit so einem spannenden Produkt zu arbeiten.<\/p>\n                        <\/div>\n                                            <\/div>\n                                                            <div class=\"cards-item-title\">\n                        <h3 class=\"big-h3\">Pawe\u0142 Mumot<\/h3>\n                        <p>Elektromonteur<\/p>\n                    <\/div>\n                                    <\/div>\n                                    <\/div>\n        <div class=\"swiper-button-prev\"><\/div>\n        <div class=\"swiper-button-next\"><\/div>\n    <\/div>\n        <\/section>\n\n\n<section\n    class=\"text-with-image-two-c  \">\n    \n    \n    <div class=\"text-with-image-two-c-wrapper\">\n        <div class=\"text-with-image-two-c-text\">\n                        <h2 >\n                                <a href=\"#contact\">\n                                        Programm \u201eE-Mobility \u2013 our passion!\u201d                                    <\/a>\n                            <\/h2>\n                                                <p class=\"text-small\">Ein Workshop-Zyklus rund um das Thema Elektromobilit\u00e4t, bei dem Fachleute von Ekoenergetyka-Polska ihre Branchenerfahrung und spannende Cases aus unserer Projektarbeit mit jungen Menschen teilen. In Zusammenarbeit mit lokalen Bildungseinrichtungen besuchen wir Schulen und Universit\u00e4ten oder laden sie zu uns ein. Zu unseren Partnern z\u00e4hlen u.a.: Universit\u00e4t Zielona G\u00f3ra, Zentrum f\u00fcr berufliche Aus- und Weiterbildung Nr. 2 \u201eELEKTRONIK\u201c, Zentrum f\u00fcr berufliche Aus- und Weiterbildung Sulech\u00f3w, Zentrum f\u00fcr berufliche Aus- und Weiterbildung \u201eElektryk\u201c in Nowa S\u00f3l ...und viele mehr!<\/p>\n                                                <a href=\"#contact\"                 class=\"button\">Let\u2019s talk                <span>\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"16\" viewBox=\"0 0 15 16\"\n                        class=\"arrow-right\">\n                        <path id=\"Vector_1\"\n                            d=\"M14.9 7.52395C14.8405 7.37051 14.7513 7.23033 14.6375 7.11145L8.3875 0.861451C8.27095 0.744903 8.13259 0.652453 7.98031 0.589377C7.82803 0.526302 7.66482 0.493837 7.5 0.493837C7.16712 0.493837 6.84788 0.626072 6.6125 0.861451C6.49595 0.977999 6.4035 1.11636 6.34042 1.26864C6.27735 1.42092 6.24488 1.58413 6.24488 1.74895C6.24488 2.08183 6.37712 2.40107 6.6125 2.63645L10.7375 6.74895L1.25 6.74895C0.918478 6.74895 0.600536 6.88065 0.366116 7.11507C0.131695 7.34949 -1.25427e-06 7.66743 -1.31224e-06 7.99895C-1.3702e-06 8.33047 0.131695 8.64841 0.366115 8.88283C0.600536 9.11725 0.918478 9.24895 1.25 9.24895L10.7375 9.24895L6.6125 13.3614C6.49534 13.4777 6.40234 13.6159 6.33888 13.7682C6.27542 13.9206 6.24275 14.0839 6.24275 14.2489C6.24275 14.414 6.27542 14.5773 6.33888 14.7297C6.40234 14.882 6.49534 15.0202 6.6125 15.1364C6.7287 15.2536 6.86695 15.3466 7.01927 15.4101C7.1716 15.4735 7.33498 15.5062 7.5 15.5062C7.66501 15.5062 7.82839 15.4735 7.98072 15.4101C8.13304 15.3466 8.27129 15.2536 8.3875 15.1364L14.6375 8.88645C14.7513 8.76757 14.8405 8.62739 14.9 8.47395C15.025 8.16962 15.025 7.82828 14.9 7.52395Z\" \/>\n                    <\/svg>\n                <\/span>\n            <\/a>\n                    <\/div>\n        <div class=\"text-with-image-two-c-image\">\n                                    <a href=\"#contact\" >\n                                <picture>\n                    <source srcset=\"https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/emobility-our-passion-768x429.jpg\"\n                        media=\"(max-width: 768px)\" \/>\n                    <source srcset=\"https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/emobility-our-passion-1024x572.jpg\"\n                        media=\"(max-width: 1024px)\" \/>\n                    <source srcset=\"https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/emobility-our-passion.jpg\"\n                        media=\"(max-width: 1920px)\" \/>\n                    <source srcset=\"https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/emobility-our-passion.jpg\" sizes=\"100vw\" \/>\n                    <img loading=\"lazy\" decoding=\"async\" width=\"1325\" height=\"740\" src=\"https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/emobility-our-passion.jpg\" class=\"img-full\" alt=\"Programm \u201eE-Mobility \u2013 our passion!\u201d - ekoenergetyka\" srcset=\"https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/emobility-our-passion.jpg 1325w, https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/emobility-our-passion-1024x572.jpg 1024w, https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/emobility-our-passion-768x429.jpg 768w\" sizes=\"auto, (max-width: 1325px) 100vw, 1325px\" \/>                <\/picture>\n                            <\/a>\n                                            <\/div>\n\n    <\/div>\n    <\/section>\n\n\n\n<section id=\"contact\" class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div style=\"height:3rem\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-kontakt\">Kontakt<\/h2>\n\n\n\n<div style=\"height:3rem\" aria-hidden=\"true\" class=\"wp-block-spacer border-heading\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<p class=\"text-big wp-block-paragraph\"><strong>Du m\u00f6chtest mehr erfahren? Melde dich bei uns:<\/strong><\/p>\n\n\n\n<p class=\"text-big wp-block-paragraph\"><a href=\"mailto:patrycja.glodna@ekoenergetyka.com\">barbara.fugiel@ekoenergetyka.com<\/a><\/p>\n\n\n\n<p class=\"text-big wp-block-paragraph\"><a href=\"tel:+48 504697332\">+48 504 697 332<\/a><\/p>\n\n\n\n<div style=\"height:1rem\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-8f761849 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.linkedin.com\/showcase\/ekoenergetyka-career\/posts\/\" target=\"_blank\" rel=\" noreferrer noopener\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2025\/05\/social_icons_www_linkedin_icon-1.svg\" alt=\"social_icons_www_linkedin_icon 1\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.facebook.com\/KarierawEkoenergetykaPolska\" target=\"_blank\" rel=\" noreferrer noopener\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2025\/05\/social_icons_www_facebook_icon-1.svg\" alt=\"social_icons_www_facebook_icon 1\"\/><\/a><\/figure>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:2rem\" aria-hidden=\"true\" class=\"wp-block-spacer border-heading\"><\/div>\n<\/div><\/section>\n\n\n<section class=\"realization-slider\">\n    <div\n        class=\"realization-slider-wrap\">\n                <div class=\"box-with-icon-title\">\n            <h2>Galerie<\/h2>\n        <\/div>\n                <div\n            class=\"swiper-container realization-slider\">\n            <div class=\"swiper-wrapper\">\n                \n                <div class=\"swiper-slide\">\n                    <div class=\"realization-wrap\"\n                        style=\"background-image: url('https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/ekoenergetyka-kariera-dsc09816.jpg')\">\n\n                        <div class=\"bc-appla\">\n                                                        <a href=\"\/wp-content\/uploads\/2025\/07\/ekoenergetyka-kariera-dsc09816.jpg\">                                                                                                                                         <\/a>\n                                                        <\/div>\n\n                    <\/div>\n                <\/div>\n                \n                <div class=\"swiper-slide\">\n                    <div class=\"realization-wrap\"\n                        style=\"background-image: url('https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/ekoenergetyka-kariera-dsc00064.jpg')\">\n\n                        <div class=\"bc-appla\">\n                                                        <a href=\"\/wp-content\/uploads\/2025\/07\/ekoenergetyka-kariera-dsc00064.jpg\">                                                                                                                                         <\/a>\n                                                        <\/div>\n\n                    <\/div>\n                <\/div>\n                \n                <div class=\"swiper-slide\">\n                    <div class=\"realization-wrap\"\n                        style=\"background-image: url('https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/ekoenergetyka-kariera-dsc06531.jpg')\">\n\n                        <div class=\"bc-appla\">\n                                                        <a href=\"\/wp-content\/uploads\/2025\/07\/ekoenergetyka-kariera-dsc06531.jpg\">                                                                                                                                         <\/a>\n                                                        <\/div>\n\n                    <\/div>\n                <\/div>\n                \n                <div class=\"swiper-slide\">\n                    <div class=\"realization-wrap\"\n                        style=\"background-image: url('https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/ekoenergetyka-kariera-dsc06577-edytuj.jpg')\">\n\n                        <div class=\"bc-appla\">\n                                                        <a href=\"\/wp-content\/uploads\/2025\/07\/ekoenergetyka-kariera-dsc06577-edytuj.jpg\">                                                                                                                                         <\/a>\n                                                        <\/div>\n\n                    <\/div>\n                <\/div>\n                \n                <div class=\"swiper-slide\">\n                    <div class=\"realization-wrap\"\n                        style=\"background-image: url('https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/07\/ekoenergetyka-kariera-dsc06623.jpg')\">\n\n                        <div class=\"bc-appla\">\n                                                        <a href=\"\/wp-content\/uploads\/2025\/07\/ekoenergetyka-kariera-dsc06623.jpg\">                                                                                                                                         <\/a>\n                                                        <\/div>\n\n                    <\/div>\n                <\/div>\n                \n            <\/div>\n            <div class=\"swiper-button-prev\"><\/div>\n            <div class=\"swiper-button-next\"><\/div>\n        <\/div>\n            <\/div>\n<\/section>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00f6chtest du dich weiterentwickeln und von den besten E-Mobility-Expert:innen lernen? Dann sind unsere Praktikums- und Traineeprogramme bei Ekoenergetyka genau das Richtige f\u00fcr dich! Kontakt Du m\u00f6chtest mehr erfahren? Melde dich bei uns: barbara.fugiel@ekoenergetyka.com +48 504 697 332<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":19696,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-49001","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Praktikum bei Ekoenergetyka | Ekoenergetyka<\/title>\n<meta name=\"description\" content=\"Ekoenergetyka - we develop and produce high power charging solutions for electric passenger cars, buses and HD vehicles.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ekoenergetyka.com\/de\/karriere\/praktikum-bei-ekoenergetyka\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Praktikum bei Ekoenergetyka\" \/>\n<meta property=\"og:description\" content=\"Ekoenergetyka - we develop and produce high power charging solutions for electric passenger cars, buses and HD vehicles.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ekoenergetyka.com\/de\/karriere\/praktikum-bei-ekoenergetyka\/\" \/>\n<meta property=\"og:site_name\" content=\"Ekoenergetyka\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ekoenergetykaPolska\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-17T06:59:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/09\/onbording-photo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1114\" \/>\n\t<meta property=\"og:image:height\" content=\"740\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ekoenergetyka.com\\\/de\\\/karriere\\\/praktikum-bei-ekoenergetyka\\\/\",\"url\":\"https:\\\/\\\/ekoenergetyka.com\\\/de\\\/karriere\\\/praktikum-bei-ekoenergetyka\\\/\",\"name\":\"Praktikum bei Ekoenergetyka | Ekoenergetyka\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ekoenergetyka.com\\\/de\\\/#website\"},\"datePublished\":\"2025-09-17T12:25:04+00:00\",\"dateModified\":\"2026-04-17T06:59:30+00:00\",\"description\":\"Ekoenergetyka - we develop and produce high power charging solutions for electric passenger cars, buses and HD vehicles.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ekoenergetyka.com\\\/de\\\/karriere\\\/praktikum-bei-ekoenergetyka\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ekoenergetyka.com\\\/de\\\/karriere\\\/praktikum-bei-ekoenergetyka\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ekoenergetyka.com\\\/de\\\/karriere\\\/praktikum-bei-ekoenergetyka\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Heim\",\"item\":\"https:\\\/\\\/ekoenergetyka.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Karriere\",\"item\":\"https:\\\/\\\/ekoenergetyka.com\\\/de\\\/karriere\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Praktikum bei Ekoenergetyka\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ekoenergetyka.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/ekoenergetyka.com\\\/de\\\/\",\"name\":\"Ekoenergetyka\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ekoenergetyka.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ekoenergetyka.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ekoenergetyka.com\\\/de\\\/#organization\",\"name\":\"Ekoenergetyka\",\"url\":\"https:\\\/\\\/ekoenergetyka.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/ekoenergetyka.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ekoenergetyka.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-sygnet-bez-tla-black-1-2.png\",\"contentUrl\":\"https:\\\/\\\/ekoenergetyka.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-sygnet-bez-tla-black-1-2.png\",\"width\":512,\"height\":512,\"caption\":\"Ekoenergetyka\"},\"image\":{\"@id\":\"https:\\\/\\\/ekoenergetyka.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ekoenergetykaPolska\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/ekoenergetyka\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCfZM_rPDdrv6D0JB-uhWi8Q\\\/videos\"],\"description\":\"Established in 2009 Poland with a sole purpose of providing charging solutions, we are one of the pioneers in the e-mobility industry. In a decade, Ekoenergetyka has grown from 2 to more than 400 employees (currently around 1,000) and has acquired customers throughout Europe and are now a Central and Eastern European leader in charging technologies.\",\"email\":\"contact@ekoenergetyka.com.pl\",\"telephone\":\"+ 48 68 328 20 68\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"501\",\"maxValue\":\"1000\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Praktikum bei Ekoenergetyka | Ekoenergetyka","description":"Ekoenergetyka - we develop and produce high power charging solutions for electric passenger cars, buses and HD vehicles.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ekoenergetyka.com\/de\/karriere\/praktikum-bei-ekoenergetyka\/","og_locale":"de_DE","og_type":"article","og_title":"Praktikum bei Ekoenergetyka","og_description":"Ekoenergetyka - we develop and produce high power charging solutions for electric passenger cars, buses and HD vehicles.","og_url":"https:\/\/ekoenergetyka.com\/de\/karriere\/praktikum-bei-ekoenergetyka\/","og_site_name":"Ekoenergetyka","article_publisher":"https:\/\/www.facebook.com\/ekoenergetykaPolska\/","article_modified_time":"2026-04-17T06:59:30+00:00","og_image":[{"width":1114,"height":740,"url":"https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2025\/09\/onbording-photo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ekoenergetyka.com\/de\/karriere\/praktikum-bei-ekoenergetyka\/","url":"https:\/\/ekoenergetyka.com\/de\/karriere\/praktikum-bei-ekoenergetyka\/","name":"Praktikum bei Ekoenergetyka | Ekoenergetyka","isPartOf":{"@id":"https:\/\/ekoenergetyka.com\/de\/#website"},"datePublished":"2025-09-17T12:25:04+00:00","dateModified":"2026-04-17T06:59:30+00:00","description":"Ekoenergetyka - we develop and produce high power charging solutions for electric passenger cars, buses and HD vehicles.","breadcrumb":{"@id":"https:\/\/ekoenergetyka.com\/de\/karriere\/praktikum-bei-ekoenergetyka\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ekoenergetyka.com\/de\/karriere\/praktikum-bei-ekoenergetyka\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ekoenergetyka.com\/de\/karriere\/praktikum-bei-ekoenergetyka\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Heim","item":"https:\/\/ekoenergetyka.com\/de\/"},{"@type":"ListItem","position":2,"name":"Karriere","item":"https:\/\/ekoenergetyka.com\/de\/karriere\/"},{"@type":"ListItem","position":3,"name":"Praktikum bei Ekoenergetyka"}]},{"@type":"WebSite","@id":"https:\/\/ekoenergetyka.com\/de\/#website","url":"https:\/\/ekoenergetyka.com\/de\/","name":"Ekoenergetyka","description":"","publisher":{"@id":"https:\/\/ekoenergetyka.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ekoenergetyka.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/ekoenergetyka.com\/de\/#organization","name":"Ekoenergetyka","url":"https:\/\/ekoenergetyka.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ekoenergetyka.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2024\/11\/cropped-sygnet-bez-tla-black-1-2.png","contentUrl":"https:\/\/ekoenergetyka.com\/wp-content\/uploads\/2024\/11\/cropped-sygnet-bez-tla-black-1-2.png","width":512,"height":512,"caption":"Ekoenergetyka"},"image":{"@id":"https:\/\/ekoenergetyka.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ekoenergetykaPolska\/","https:\/\/www.linkedin.com\/company\/ekoenergetyka","https:\/\/www.youtube.com\/channel\/UCfZM_rPDdrv6D0JB-uhWi8Q\/videos"],"description":"Established in 2009 Poland with a sole purpose of providing charging solutions, we are one of the pioneers in the e-mobility industry. In a decade, Ekoenergetyka has grown from 2 to more than 400 employees (currently around 1,000) and has acquired customers throughout Europe and are now a Central and Eastern European leader in charging technologies.","email":"contact@ekoenergetyka.com.pl","telephone":"+ 48 68 328 20 68","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"501","maxValue":"1000"}}]}},"_links":{"self":[{"href":"https:\/\/ekoenergetyka.com\/de\/wp-json\/wp\/v2\/pages\/49001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ekoenergetyka.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ekoenergetyka.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ekoenergetyka.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ekoenergetyka.com\/de\/wp-json\/wp\/v2\/comments?post=49001"}],"version-history":[{"count":5,"href":"https:\/\/ekoenergetyka.com\/de\/wp-json\/wp\/v2\/pages\/49001\/revisions"}],"predecessor-version":[{"id":58926,"href":"https:\/\/ekoenergetyka.com\/de\/wp-json\/wp\/v2\/pages\/49001\/revisions\/58926"}],"up":[{"embeddable":true,"href":"https:\/\/ekoenergetyka.com\/de\/wp-json\/wp\/v2\/pages\/19696"}],"wp:attachment":[{"href":"https:\/\/ekoenergetyka.com\/de\/wp-json\/wp\/v2\/media?parent=49001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}